{"id":9214,"date":"2022-10-21T20:57:33","date_gmt":"2022-10-21T18:57:33","guid":{"rendered":"https:\/\/mecm-schulung.de\/?page_id=9214"},"modified":"2022-12-05T19:30:43","modified_gmt":"2022-12-05T18:30:43","slug":"elementor-9214","status":"publish","type":"page","link":"https:\/\/intune-schulung.de\/de\/elementor-9214\/","title":{"rendered":"Elementor #9214"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9214\" class=\"elementor elementor-9214\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0fb21e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0fb21e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f912904\" data-id=\"f912904\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d76d6f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d76d6f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b7be86\" data-id=\"1b7be86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-920470b elementor-widget elementor-widget-edubin-cta\" data-id=\"920470b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-cta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    \n    <div class=\"edubin-cta-1\">\n        <div class=\"cta-content\">\n\n                    <div class=\"cta-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-phone-volume\"><\/i>            <\/div>\n    \n            <div class=\"cta-text\">\n                <p>Rufen Sie F\u00fcr Jede Abfrage<\/p>\n                <span class=\"number\">321 325 5678<\/span>\n            <\/div>\n        \n        <\/div>\n    <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f7c950f\" data-id=\"f7c950f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca34c35 elementor-widget elementor-widget-edubin-cta\" data-id=\"ca34c35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-cta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    \n    <div class=\"edubin-cta-1\">\n        <div class=\"cta-content\">\n\n        \n        <\/div>\n    <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df3853c\" data-id=\"df3853c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f48555c elementor-widget elementor-widget-heading\" data-id=\"f48555c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hallo! Ich bin Minderj\u00e4hrigen Ehre<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82dfd15 elementor-widget elementor-widget-heading\" data-id=\"82dfd15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">An executive Life \n&amp; Career Coaching professional mentor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85232fe elementor-widget elementor-widget-text-editor\" data-id=\"85232fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieses Thema enth\u00e4lt alle notwendigen Seiten des onlineLorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem quibibendum auci elit Nachteile Zeitstufen ipsutis sem nibh id elit. Duis sed odio sit amet nibh vulputate cursus a sit amet<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a94d09 elementor-align-left elementor-tablet-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"4a94d09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Erfahren Sie Mehr \u00dcber Mich<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-889ee86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"889ee86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0cc75b\" data-id=\"a0cc75b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39b8f62 elementor-widget elementor-widget-heading\" data-id=\"39b8f62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Der Zertifizierte Coach-Programm<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb7140 elementor-widget elementor-widget-heading\" data-id=\"9fb7140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">W\u00e4hlen Sie Ihren coach training basiert auf dem Programm <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c320f4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c320f4c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a792a1f\" data-id=\"a792a1f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a9a0ad elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"0a9a0ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/OH469.png\" title=\"OH469.png\" alt=\"OH469.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Karriere Coach                    <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2bd1550\" data-id=\"2bd1550\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80353f4 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"80353f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II932.png\" title=\"II932.png\" alt=\"II932.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Karriere-Planung                     <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-747da7b\" data-id=\"747da7b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76c10f0 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"76c10f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/IIP032.png\" title=\"IIP032.png\" alt=\"IIP032.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Beratung                     <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c76b038\" data-id=\"c76b038\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c55693 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"2c55693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/OI832.png\" title=\"OI832.png\" alt=\"OI832.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Beratung                    <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-860f68b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"860f68b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ab78cdb\" data-id=\"ab78cdb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-081cbc4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"081cbc4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a7d85a0\" data-id=\"a7d85a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-070e2d5 elementor-widget elementor-widget-heading\" data-id=\"070e2d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die Bereitstellung der besten Karriere-coaching-services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e13fc88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e13fc88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fb1da03\" data-id=\"fb1da03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1c0ed7 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"a1c0ed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"38\" height=\"40\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II0313.png\" class=\"attachment-thumbnail size-thumbnail wp-image-7906\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f737415 elementor-widget__width-auto elementor-widget elementor-widget-edubin-counter\" data-id=\"f737415\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"elementor-counter\">\n\n            <div class=\"elementor-counter-number-wrapper-no\">\n                <span class=\"elementor-counter-number-prefix\"><\/span>\n                <span class=\"eb_counting\" data-count=\"700\">0<\/span>\n                \n                <span class=\"elementor-counter-number-suffix\">+<\/span>\n            <\/div>\n                            <div class=\"elementor-counter-title\">Online-Kurse<\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d3a9c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d3a9c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5a0f358\" data-id=\"5a0f358\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c42f49 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"7c42f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"30\" height=\"40\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II8324.png\" class=\"attachment-thumbnail size-thumbnail wp-image-7907\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3494e42 elementor-widget__width-auto elementor-widget elementor-widget-edubin-counter\" data-id=\"3494e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"elementor-counter\">\n\n            <div class=\"elementor-counter-number-wrapper-no\">\n                <span class=\"elementor-counter-number-prefix\"><\/span>\n                <span class=\"eb_counting\" data-count=\"168\">0<\/span>\n                \n                <span class=\"elementor-counter-number-suffix\">+<\/span>\n            <\/div>\n                            <div class=\"elementor-counter-title\">Weltweit Lernenden<\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bf1473e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf1473e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6315195\" data-id=\"6315195\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ac16f8 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"1ac16f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"38\" height=\"40\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II903.png\" class=\"attachment-thumbnail size-thumbnail wp-image-7908\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-959953d elementor-widget__width-auto elementor-widget elementor-widget-edubin-counter\" data-id=\"959953d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"elementor-counter\">\n\n            <div class=\"elementor-counter-number-wrapper-no\">\n                <span class=\"elementor-counter-number-prefix\"><\/span>\n                <span class=\"eb_counting\" data-count=\"100\">0<\/span>\n                \n                <span class=\"elementor-counter-number-suffix\">%<\/span>\n            <\/div>\n                            <div class=\"elementor-counter-title\">Kundenzufriedenheit<\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b09b147\" data-id=\"b09b147\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8454434 elementor-widget elementor-widget-edubin-contactform-addons\" data-id=\"8454434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-contactform-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-form-wrapper\" >\n\n                            <div class=\"wpcf7-head-container\">\n                                            <div class=\"wpcf7-title\">Lassen Sie Uns Eine Nachricht<\/div>\n                    \n                                            <div class=\"wpcf7-description\">Wie Kann ich Ihnen Helfen!<\/div>\n                    \n                <\/div>\n            \n                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8773-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"8773\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/9214#wpcf7-f8773-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/9214#wpcf7-f8773-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8773\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8773-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vorname\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nachname\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ihre E-Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Ihre Nachricht\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Nachricht Senden\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<\/div>\n            <\/div>\n\n                        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8f6c20 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8f6c20\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca454c9\" data-id=\"ca454c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7da3721 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7da3721\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5ac1bbd\" data-id=\"5ac1bbd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74c0aea elementor-widget elementor-widget-heading\" data-id=\"74c0aea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Was Sie sagen,<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc0ce5e elementor-widget elementor-widget-heading\" data-id=\"dc0ce5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00f6ren, was die Leute sagen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95fd947 elementor-widget elementor-widget-edubin-testimonial-addons\" data-id=\"95fd947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-testimonial-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div class=\"edubin-testi-6 edubin-testimonial-style-6 edubin-carousel-dot-1 edubin-carousel-nav-1 edubin-testimonial-activation edubin-carousel-style\" data-settings=\"{&quot;arrows&quot;:false,&quot;arrow_prev_txt&quot;:null,&quot;arrow_next_txt&quot;:null,&quot;dots&quot;:true,&quot;autoplay&quot;:false,&quot;autoplay_speed&quot;:3000,&quot;animation_speed&quot;:300,&quot;pause_on_hover&quot;:true,&quot;center_mode&quot;:false,&quot;center_padding&quot;:0,&quot;testimonial_style_ck&quot;:6,&quot;display_columns&quot;:1,&quot;scroll_columns&quot;:1,&quot;tablet_width&quot;:786,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}\">\n                                    <div class=\"edubin-testi-single layout-6\">\n                        <div class=\"testimonial-thum\">\n                            <div class=\"testimonal-image\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"400\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826.jpg\" class=\"attachment-medium_large size-medium_large wp-image-7911\" alt=\"\" srcset=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826.jpg 368w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826-300x326.jpg 300w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826-276x300.jpg 276w\" sizes=\"(max-width: 368px) 100vw, 368px\" \/><\/div>                            <div class=\"testimonial-shape\"><\/div>\n                        <\/div>\n                        <div class=\"testimonial-cont\">\n                            <i class=\"fas fa-quote-right\"><\/i>\n                                <p>I am grateful for your wonderful course! Your tutors are the best, and I am completely satisfied with the level of professional teaching. I recommend these courses to everyone, and wish you, guys, luck with the new studies!<\/p>                        <div class=\"testi-name-degree\">\n                            <h6 class=\"name\">James Smith<\/h6><p class=\"degree\">Bsc, Engineering<\/p>                        <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"edubin-testi-single layout-6\">\n                        <div class=\"testimonial-thum\">\n                            <div class=\"testimonal-image\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"400\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/IIT92.jpg\" class=\"attachment-medium_large size-medium_large wp-image-7912\" alt=\"\" srcset=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/IIT92.jpg 368w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/IIT92-300x326.jpg 300w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/IIT92-276x300.jpg 276w\" sizes=\"(max-width: 368px) 100vw, 368px\" \/><\/div>                            <div class=\"testimonial-shape\"><\/div>\n                        <\/div>\n                        <div class=\"testimonial-cont\">\n                            <i class=\"fas fa-quote-right\"><\/i>\n                                <p>Lorem ipsum dolor sit amet consectetur adipisicing elit sed do eiusmod tempor incididunt ut labore et dolore Lorem ipsum dolor sit amet. It is a very good course for those who are the beginner. luck with the new studies!<\/p>                        <div class=\"testi-name-degree\">\n                            <h6 class=\"name\">Monica Blews<\/h6><p class=\"degree\">Bcs, Teacher <\/p>                        <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"edubin-testi-single layout-6\">\n                        <div class=\"testimonial-thum\">\n                            <div class=\"testimonal-image\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"400\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826.jpg\" class=\"attachment-large size-large wp-image-7911\" alt=\"\" srcset=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826.jpg 368w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826-300x326.jpg 300w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/TT826-276x300.jpg 276w\" sizes=\"(max-width: 368px) 100vw, 368px\" \/><\/div>                            <div class=\"testimonial-shape\"><\/div>\n                        <\/div>\n                        <div class=\"testimonial-cont\">\n                            <i class=\"fas fa-quote-right\"><\/i>\n                                <p>I am grateful for your wonderful course! Your tutors are the best, and I am completely satisfied with the level of professional teaching. I recommend these courses to everyone, and wish you, guys, luck with the new studies!<\/p>                        <div class=\"testi-name-degree\">\n                            <h6 class=\"name\">John Dowson<\/h6><p class=\"degree\">Math Teacher<\/p>                        <\/div>\n                        <\/div>\n                    <\/div>\n                            <\/div> <!-- End testimonial style 3 -->\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c82155 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c82155\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0b86ae\" data-id=\"d0b86ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc85666 elementor-widget elementor-widget-heading\" data-id=\"dc85666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Meine Artikel <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97a91f3 elementor-widget elementor-widget-heading\" data-id=\"97a91f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Neueste aus dem Blog<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc7bc0 elementor-widget elementor-widget-edubin-latest-post\" data-id=\"4dc7bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-latest-post.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"row edubin-latest-news layout-1\">\n\n            \n                       \n                \n          \n                    <div class=\"col-lg-3\">\n                        <div class=\"single-news\">\n                                                            <div class=\"news-thum\">\n                                    <a href=\"https:\/\/intune-schulung.de\/de\/how-to-learn-english-fast-and-easy\/\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/05\/BL032-1024x683.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/05\/BL032-1024x683.jpeg 1024w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/05\/BL032-300x200.jpeg 300w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/05\/BL032-600x400.jpeg 600w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/05\/BL032-768x512.jpeg 768w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/05\/BL032-1536x1024.jpeg 1536w, https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/05\/BL032.jpeg 1600w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>                                    <\/a>\n                                <\/div>\n                            \n                                <div class=\"news-cont\">\n                                                                        <ul>\n                                                                                                                    <\/ul>\n                                                                            <a href=\"https:\/\/intune-schulung.de\/de\/how-to-learn-english-fast-and-easy\/\"><h3 class=\"news-title\">Wie Lernen Sie Englisch Schnell und Einfach<\/h3><\/a>\n                                                                                                            \n                                <\/div>\n                            <\/div> <!-- single news -->\n                    <\/div>\n      \n\n                    \n                                 \n\n    \n                                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5429d7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5429d7e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29355cc\" data-id=\"29355cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c6d605 elementor-widget elementor-widget-edubin-section-4\" data-id=\"1c6d605\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-section-4.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <!-- Hero Start -->\n        <div class=\"edubin-hero-4\">\n            <div class=\"shape-1\">\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1401px\" height=\"1049px\">\n                    <path d=\"M127.828,0.1 L1273.171,0.1 C1343.769,0.1 1400.999,57.275 1400.999,127.927 L1209.257,921.72 C1183.691,1009.634 1152.26,1048.999 1081.428,1048.999 L127.828,1048.999 C57.230,1048.999 0.0,991.724 0.0,921.72 L0.0,127.927 C0.0,57.275 57.230,0.1 127.828,0.1 Z\" \/>\n                <\/svg>\n            <\/div>\n            <div class=\"shape-2\">\n                <svg width=\"661px\" height=\"716px\">\n                    <path d=\"M609.525,302.24 C482.12,224.115 277.82,98.906 145.932,18.774 C72.32,-26.376 19.382,13.512 16.313,113.275 C11.487,270.135 4.452,498.778 0.195,637.148 C-2.26,709.363 39.95,734.489 103.670,700.370 C238.249,629.263 468.331,507.696 607.437,434.198 C677.560,397.147 678.308,344.49 609.525,302.24 Z\" \/>\n                <\/svg>\n            <\/div>\n            <div class=\"shape-3\">\n                <div class=\"sign\" data-aos=\"fade-up\" data-aos-delay=\"600\">\n                                    <\/div>\n            <\/div>\n            <div class=\"shape-5\"><\/div>\n            <div class=\"shape-6\">\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1057px\" height=\"791px\">\n                    <path d=\"M960.558,790.999 L96.441,790.999 C43.178,790.999 0.0,747.811 0.0,694.536 L144.662,96.463 C163.950,29.682 187.840,0.0 241.103,0.0 L960.558,0.0 C1013.821,0.0 1056.999,43.187 1056.999,96.463 L1056.999,694.536 C1056.999,747.811 1013.821,790.999 960.558,790.999 Z\" \/>\n                <\/svg>\n            <\/div>\n            <div class=\"shape-7\">\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1057px\" height=\"791px\">\n                    <path d=\"M960.558,790.999 L96.441,790.999 C43.178,790.999 0.0,747.811 0.0,694.536 L144.662,96.462 C163.950,29.682 187.840,0.0 241.103,0.0 L960.558,0.0 C1013.821,0.0 1056.999,43.187 1056.999,96.462 L1056.999,694.536 C1056.999,747.811 1013.821,790.999 960.558,790.999 Z\" \/>\n                <\/svg>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"row\">\n                    <div class=\"col-lg-12\">\n                        <!-- Hero Content Start -->\n                        <div class=\"hero-content\">\n\n                            \n                                                             <h2 class=\"title\" data-aos=\"fade-up\" data-aos-delay=\"800\"><span>Microsoft<\/span> <span>Endpoint Manager<\/span> <span>Schulungen<\/span><\/h2>\n                            \n                            \n                            <div class=\"hero-btn\" data-aos=\"fade-up\" data-aos-delay=\"900\">\n                                                            <a class=\"here-btn edubin-btn-3\"  href=\"#\">Kostenloses E-Book herunterladen<\/a>\n                            \n                            <div class=\"shape-4\">\n                                <div class=\"sign\" data-aos=\"fade-up\" data-aos-delay=\"600\">\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                        <!-- Hero Content End -->\n                    <\/div>\n                <\/div>\n            <\/div>\n\n        <\/div>\n        <!-- Hero End -->\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8ed298 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8ed298\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cf727a\" data-id=\"2cf727a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5682b98 elementor-widget elementor-widget-spacer\" data-id=\"5682b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-372e689 elementor-widget elementor-widget-heading\" data-id=\"372e689\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Der Zertifizierte Coach-Programm<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-907aabe elementor-widget elementor-widget-heading\" data-id=\"907aabe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">W\u00e4hlen Sie Ihren coach training basiert auf dem Programm <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5065f9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5065f9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-03472b8\" data-id=\"03472b8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cc4d05 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"7cc4d05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/OH469.png\" title=\"OH469.png\" alt=\"OH469.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Karriere Coach                    <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9764add\" data-id=\"9764add\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48c8c14 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"48c8c14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II932.png\" title=\"II932.png\" alt=\"II932.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Karriere-Planung                     <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-727baf5\" data-id=\"727baf5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2d2359 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"f2d2359\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/IIP032.png\" title=\"IIP032.png\" alt=\"IIP032.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Beratung                     <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-140d68a\" data-id=\"140d68a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6433ac4 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"6433ac4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\">\n\n                \n                            <div class=\"icon-shape-wrap\"><\/div>\n\n                            <i><img decoding=\"async\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/OI832.png\" title=\"OI832.png\" alt=\"OI832.png\" loading=\"lazy\" \/><\/i>\n\n                       \n                <\/a>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <a href=\"https:\/\/thepixelcurve.com\/wp\/edubin\/tutor\/about-us\/\" >\n                        Beratung                    <\/a>\n                <\/h3>\n                                    <p class=\"elementor-icon-box-description\">\n                        Lorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem                    <\/p>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e56fd5b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e56fd5b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68483d7\" data-id=\"68483d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17881d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17881d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d319af5\" data-id=\"d319af5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2c8624 elementor-widget elementor-widget-heading\" data-id=\"e2c8624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die Bereitstellung der besten Karriere-coaching-services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0a42ea7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a42ea7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-09b173c\" data-id=\"09b173c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0b6158 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"c0b6158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"38\" height=\"40\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II0313.png\" class=\"attachment-thumbnail size-thumbnail wp-image-7906\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3be3ffe elementor-widget__width-auto elementor-widget elementor-widget-edubin-counter\" data-id=\"3be3ffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"elementor-counter\">\n\n            <div class=\"elementor-counter-number-wrapper-no\">\n                <span class=\"elementor-counter-number-prefix\"><\/span>\n                <span class=\"eb_counting\" data-count=\"700\">0<\/span>\n                \n                <span class=\"elementor-counter-number-suffix\">+<\/span>\n            <\/div>\n                            <div class=\"elementor-counter-title\">Online-Kurse<\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-65ffe93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65ffe93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-21ab34f\" data-id=\"21ab34f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b1412b elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"1b1412b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"30\" height=\"40\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II8324.png\" class=\"attachment-thumbnail size-thumbnail wp-image-7907\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcfa9f0 elementor-widget__width-auto elementor-widget elementor-widget-edubin-counter\" data-id=\"bcfa9f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"elementor-counter\">\n\n            <div class=\"elementor-counter-number-wrapper-no\">\n                <span class=\"elementor-counter-number-prefix\"><\/span>\n                <span class=\"eb_counting\" data-count=\"168\">0<\/span>\n                \n                <span class=\"elementor-counter-number-suffix\">+<\/span>\n            <\/div>\n                            <div class=\"elementor-counter-title\">Weltweit Lernenden<\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c22de5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c22de5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cdab63f\" data-id=\"cdab63f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e183dd4 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"e183dd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"38\" height=\"40\" src=\"https:\/\/intune-schulung.de\/wp-content\/uploads\/2021\/12\/II903.png\" class=\"attachment-thumbnail size-thumbnail wp-image-7908\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-118c0c7 elementor-widget__width-auto elementor-widget elementor-widget-edubin-counter\" data-id=\"118c0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"elementor-counter\">\n\n            <div class=\"elementor-counter-number-wrapper-no\">\n                <span class=\"elementor-counter-number-prefix\"><\/span>\n                <span class=\"eb_counting\" data-count=\"100\">0<\/span>\n                \n                <span class=\"elementor-counter-number-suffix\">%<\/span>\n            <\/div>\n                            <div class=\"elementor-counter-title\">Kundenzufriedenheit<\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cd24027\" data-id=\"cd24027\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d342361 elementor-widget elementor-widget-edubin-contactform-addons\" data-id=\"d342361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-contactform-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-form-wrapper\" >\n\n                            <div class=\"wpcf7-head-container\">\n                                            <div class=\"wpcf7-title\">Lassen Sie Uns Eine Nachricht<\/div>\n                    \n                                            <div class=\"wpcf7-description\">Wie Kann ich Ihnen Helfen!<\/div>\n                    \n                <\/div>\n            \n                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8773-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"8773\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/9214#wpcf7-f8773-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/9214#wpcf7-f8773-o2\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8773\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8773-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vorname\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nachname\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ihre E-Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Ihre Nachricht\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Nachricht Senden\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<\/div>\n            <\/div>\n\n                        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Call For Any Query 321 325 5678 Hello! I&#8217;m Minor honor An executive Life &#038; Career Coaching professional mentor This theme includes all the necessary pages of the onlineLorem ipsum gravida nibh vel velit auctor aliquetn sollicitudirem quibibendum auci elit cons equat ipsutis sem nibh [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9214","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/pages\/9214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/comments?post=9214"}],"version-history":[{"count":11,"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/pages\/9214\/revisions"}],"predecessor-version":[{"id":9494,"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/pages\/9214\/revisions\/9494"}],"wp:attachment":[{"href":"https:\/\/intune-schulung.de\/de\/wp-json\/wp\/v2\/media?parent=9214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}